{"id":10019,"date":"2018-05-11T07:00:00","date_gmt":"2018-05-11T06:00:00","guid":{"rendered":"https:\/\/swisstabletennis.ch\/neu\/les-finlandais-sont-les-vedettes-du-tennis-de-table-sur-youtube\/"},"modified":"2022-06-24T08:56:59","modified_gmt":"2022-06-24T07:56:59","slug":"les-finlandais-sont-les-vedettes-du-tennis-de-table-sur-youtube","status":"publish","type":"post","link":"https:\/\/www.swisstabletennis.ch\/fr\/les-finlandais-sont-les-vedettes-du-tennis-de-table-sur-youtube\/","title":{"rendered":"Les Finlandais sont les vedettes du tennis de table sur Youtube"},"content":{"rendered":"<p class=\"titel\"><strong><figure id=\"attachment_10016\" aria-describedby=\"caption-attachment-10016\" style=\"width: 520px\" class=\"wp-caption alignleft\"><a class=\"jcepopup noicon\" href=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2018\/05\/Bild.jpg\" data-mediabox=\"1\" data-mediabox-title=\"Les trois jeunes hommes de Pongfinity\" data-mediabox-caption=\"Emil, Miikka et Otto\"><img fetchpriority=\"high\" decoding=\"async\" class=\" alignleft size-full wp-image-10017\" style=\"margin-right: 20px; margin-bottom: 10px; float: left;\" src=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2018\/05\/Bild.jpg\" alt=\"Bild\" width=\"520\" height=\"347\" \/><\/a><figcaption id=\"caption-attachment-10016\" class=\"wp-caption-text\">Les trois jeunes hommes de Pongfinity<\/figcaption><\/figure><\/strong>Les Finlandais sont les vedettes du tennis de table sur Youtube<\/p>\n<p><span class=\"untertitel\">Presque 80&rsquo;000 abonn\u00e9s sur Youtube, jusqu\u2019\u00e0 deux millions de clics par vid\u00e9o \u2013 on ne parle pas d\u2019une star du rock, mais de trois Finlandais qui sont en train de devenir c\u00e9l\u00e8bres avec des vid\u00e9os de tennis de table qu\u2019ils publient sur le portail vid\u00e9o. Sidespin discutait avec les jeunes hommes de Pongfinity.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>Texte : Annina H\u00e4usli \/ photo : zvg<\/p>\n<p>&nbsp;<\/p>\n<p>Est-il possible d\u2019\u00e9teindre une bougie avec une balle de tennis de table ? Ou peut-on utiliser un coussin au lieu d\u2019une raquette ? C\u2019est sur ce genre de questions que le canal Youtube Pongfinity se penche. La premi\u00e8re vid\u00e9o avait \u00e9t\u00e9 publi\u00e9e en 2012. Depuis, ce canal ne cesse de grandir. C\u2019est \u00e0 trois Finlandais de Helsinki que l\u2019on doit ces vid\u00e9os.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abLorsque nous avons commenc\u00e9 avec ces vid\u00e9os, nous ne nous imaginions pas que cinq ans plus tard, nous serons toujours l\u00e0\u00bb, se souvient Emil Rantatulkkila (24). Avec deux amis, Miikka O&rsquo;Connor (22) et Otto Tennil\u00e4 (25) (qui avait jou\u00e9 contre la Suisse avec l\u2019\u00e9quipe nationale finlandaise en mars \u00e0 Gen\u00e8ve), il avait d\u00e9cid\u00e9 en 2012 de se filmer lors d\u2019une s\u00e9ance d\u2019entra\u00eenement. \u00abDans ce contexte, nous essayions diff\u00e9rents trickshots et nous en faisions un floril\u00e8ge.\u00bb Au d\u00e9but, la vid\u00e9o \u00e9tait destin\u00e9e seulement \u00e0 des amis, mais les r\u00e9actions de ceux-ci avaient incit\u00e9 le trio \u00e0 la publier sur Youtube. \u00abEnsuite, les m\u00e9dias finlandaises s\u2019int\u00e9ressaient \u00e9galement \u00e0 cette vid\u00e9o et nous remarquions qu\u2019avec ce genre de vid\u00e9os, nous pourrions contribuer \u00e0 rendre le tennis de table plus populaire.\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pas aussi simple que \u00e7a en a l\u2019air<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>C\u2019est pour cette raison et gr\u00e2ce aux nombreuses r\u00e9actions positives qu\u2019ils sont donc toujours l\u00e0 en publiant r\u00e9guli\u00e8rement de nouvelles vid\u00e9os sur Youtube. Dans ce contexte, ils ont aussi besoin de l\u2019aide des spectateurs qui peuvent leur faire des suggestions pour de nouvelles vid\u00e9os en mettant des commentaires.<\/p>\n<p>&nbsp;<\/p>\n<p>Avec le succ\u00e8s, le travail n\u00e9cessaire pour une vid\u00e9o a \u00e9galement augment\u00e9. Aujourd\u2019hui, ils ont parfois besoin de 30 heures pour enregistrer une vid\u00e9o. Cela englobe les pr\u00e9paratifs, le tournage, le montage et l\u2019\u00e9dition. \u00c0 noter que le travail apr\u00e8s le tournage prend clairement le plus de temps. \u00abPour les \u00abtricks\u00bb, nous avons parfois besoin de quelques minutes, mais cela peut prendre une demi-heure\u00bb, pr\u00e9cise Emil. Mais tout ne fonctionne \u00e9videmment pas toujours d\u2019entr\u00e9e, comme le d\u00e9montre ce b\u00eatisier :<\/p>\n<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/U48nJvfhO5k\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Les trois jeunes hommes se sont par ailleurs connus lorsqu\u2019ils faisaient partie du cadre national finlandais. Tandis qu\u2019Otto et Miikka disputent toujours des tournois de l\u2019\u00e9lite \u2013 Otto participait entre autres aussi aux CM par \u00e9quipes<em> <\/em>\u2013 Emil dut mettre un terme \u00e0 sa carri\u00e8re de joueur professionnel suite \u00e0 des blessures qui le faisaient prendre trop de retard.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Au contact avec l\u2019\u00e9lite mondiale<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Les derniers CM de l\u2019\u00e9lite \u00e0 D\u00fcsseldorf o\u00f9 il \u00e9tait en direct sur place \u00e9taient une exp\u00e9rience particuli\u00e8re pour Emil. \u00abGr\u00e2ce \u00e0 mon semestre d\u2019\u00e9change \u00e0 Singapour o\u00f9 se trouve le quartier g\u00e9n\u00e9ral de l\u2019ITTF, le contact avec le service de marketing \u00e9tait \u00e9tabli\u00bb, se souvient Emil. Les choses en ont ensuite entra\u00een\u00e9 d\u2019autres et pour finir, il pouvait filmer les meilleurs joueurs du monde lorsqu\u2019ils essayaient des trickshots.<\/p>\n<p>&nbsp;<\/p>\n<p>Quand Emil, Miikka et Otto ne se trouvent pas dans la salle de tennis de table pour Pongfinity, ils vont au travail et suivent leurs \u00e9tudes \u00e0 l\u2019universit\u00e9. Mais leurs vid\u00e9os leur permettent aussi de gagner un peu d\u2019argent. Ils ont m\u00eame pu mettre sur pied leur propre petit fanshop. Et les jeunes hommes sont tr\u00e8s motiv\u00e9s \u00e0 continuer \u00e0 produire toujours de nouvelles vid\u00e9os \u00e9galement \u00e0 l\u2019avenir. \u00abEt qui sait, peut-\u00eatre que nous pourrons m\u00eame un jour en vivre\u00bb, d\u00e9clare Emil.<\/p>\n<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/TSngI2VfHAU\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Autres article dans cette \u00e9dition:<\/strong><\/p>\n<p><a href=\"https:\/\/www.swisstabletennis.ch\/portraet-elias-hardmeier\/\" target=\"_blank\" rel=\"noopener\">Portrait Elias Hardmeier<\/a><\/p>\n<p><a href=\"https:\/\/www.swisstabletennis.ch\/mentales-training-im-tischtennis\/\" target=\"_blank\" rel=\"noopener\">Un livre r\u00e9ussi pour les joueurs et les coachs<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Finlandais sont les vedettes du tennis de table sur Youtube Presque 80&rsquo;000 abonn\u00e9s sur Youtube, jusqu\u2019\u00e0 deux millions de&hellip;<\/p>\n","protected":false},"author":8,"featured_media":10016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[110],"tags":[],"class_list":["post-10019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sidespin"],"_links":{"self":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts\/10019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/comments?post=10019"}],"version-history":[{"count":0,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts\/10019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/media\/10016"}],"wp:attachment":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/media?parent=10019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/categories?post=10019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/tags?post=10019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}