{"id":44019,"date":"2025-10-29T08:42:58","date_gmt":"2025-10-29T07:42:58","guid":{"rendered":"https:\/\/www.swisstabletennis.ch\/?p=44019"},"modified":"2025-10-29T14:15:52","modified_gmt":"2025-10-29T13:15:52","slug":"sttl-men-lugano-toujours-invaincu","status":"publish","type":"post","link":"https:\/\/www.swisstabletennis.ch\/fr\/sttl-men-lugano-toujours-invaincu\/","title":{"rendered":"STTL Men : Lugano toujours invaincu"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"44019\" class=\"elementor elementor-44019 elementor-43966\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e24fc49 e-flex e-con-boxed e-con e-parent\" data-id=\"7e24fc49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ea57137 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"5ea57137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6>Les 25 et 26 octobre ont eu lieu les 3e et 4e tours de la Swiss Table Tennis League Men : tandis que Lugano s&rsquo;installe confortablement en t\u00eate du classement, une course au coude \u00e0 coude se profile pour les places suivantes.<\/h6><p style=\"text-align: justify;\">Texte : Sebastian Lauener \/ Photos : Ren\u00e9 Zwald (<a href=\"https:\/\/www.flickr.com\/photos\/142862027@N07\/albums\/72177720329942610\">album photo<\/a>)<\/p><p style=\"text-align: justify;\"><span style=\"background-color: transparent; font-size: 14px; letter-spacing: 0.26px;\">\u00a0<\/span><\/p><p style=\"text-align: justify;\"><span style=\"background-color: transparent; font-size: 14px; letter-spacing: 0.26px;\">Avec deux victoires, le champion de 2023 et 2024 conserve la t\u00eate du classement : gr\u00e2ce \u00e0 ses victoires 6:2 \u00e0 Carouge et 6:3 \u00e0 ZZ-Lancy, Lugano bat ce week-end \u00e0 Gen\u00e8ve les deux finalistes de la saison pr\u00e9c\u00e9dente et reste la seule \u00e9quipe sans d\u00e9faite. Le renfort Carlo Rossi (A21) continue de s&rsquo;av\u00e9rer \u00eatre un coup de chance pour les Tessinois et ne laisse aucun point en route dans les six simples et les deux doubles avec le gaucher Paolo Bisi (A20). Bisi et le capitaine de l&rsquo;\u00e9quipe Simone Spinicchia (A19), avec deux victoires en simple chacun, ont compl\u00e9t\u00e9 le tableau. Avec ce d\u00e9but de saison en force, Lugano souligne ses ambitions de reconqu\u00e9rir le titre.<\/span><\/p><figure id=\"attachment_37912\" aria-describedby=\"caption-attachment-37912\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-37912 size-full\" src=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-scaled.jpg 2560w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-300x200.jpg 300w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-1024x683.jpg 1024w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-768x512.jpg 768w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-391x260.jpg 391w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-1536x1024.jpg 1536w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-2048x1365.jpg 2048w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-370x247.jpg 370w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-818x545.jpg 818w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-406x271.jpg 406w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-600x400.jpg 600w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-500x333.jpg 500w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-400x267.jpg 400w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/03\/Spinicchia-NLA-11_23-1-32x21.jpg 32w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-37912\" class=\"wp-caption-text\">Simone Spinicchia (Lugano)<\/figcaption><\/figure><p style=\"text-align: justify;\"><span style=\"font-size: 14px; background-color: transparent; letter-spacing: 0.26px;\">Les deux finalistes genevois suivent dans les places suivantes, ZZ-Lancy occupant la troisi\u00e8me place avec le meilleur ratio de matchs, suivi de Carouge et des Young Stars ZH, qui ont tous le m\u00eame nombre de points. ZZ-Lancy n&rsquo;a disput\u00e9 qu&rsquo;un seul match ce week-end et s&rsquo;est inclin\u00e9 face \u00e0 Lugano, mais Lo\u00efc Stoll (A20) a au moins confirm\u00e9 son bon classement en remportant deux victoires contre Bisi et Spinicchia. Chaitanya Vepa a remport\u00e9 la troisi\u00e8me victoire lors de la d\u00e9faite 3:6, \u00e9galement contre Bisi.<\/span><\/p><figure id=\"attachment_43996\" aria-describedby=\"caption-attachment-43996\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-43996 size-full\" src=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-scaled.jpg 2560w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-300x200.jpg 300w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-1024x683.jpg 1024w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-768x512.jpg 768w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-391x260.jpg 391w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-1536x1024.jpg 1536w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-2048x1365.jpg 2048w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-370x247.jpg 370w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-818x545.jpg 818w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-406x271.jpg 406w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-600x400.jpg 600w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-500x333.jpg 500w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-400x267.jpg 400w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/022a7327_54849594819_o-32x21.jpg 32w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-43996\" class=\"wp-caption-text\">Lo\u00efc Stoll (ZZ-Lancy)<\/figcaption><\/figure><p style=\"text-align: justify;\"><span style=\"font-size: 14px; background-color: transparent; letter-spacing: 0.26px;\">Carouge s&rsquo;incline face \u00e0 Lugano, mais trois des quatre matchs en cinq sets reviennent aux visiteurs tessinois. Le match perdu 2:6 aurait donc pu \u00eatre nettement plus serr\u00e9. Gr\u00e2ce \u00e0 leurs deux victoires, les Young Stars ZH se hissent dans les rangs des play-offs : lors des deux matchs \u00e0 domicile contre Neuhausen (6:1) et Rio-Star Muttenz (6:2), les Zurichois ne laissent rien passer. Noe Keusch (A20) reste invaincu en simple ce week-end pour les Young Stars, mais doit s&rsquo;incliner dimanche en double avec Filip Karin (A19). Barish Moullet (A20), \u00e9galement tr\u00e8s performant en simple avec un bilan de 4:1, et Lars Posch (A19), qui s&rsquo;incline malheureusement \u00e0 deux reprises au cinqui\u00e8me set, contribuent \u00e9galement aux victoires gr\u00e2ce \u00e0 leurs points.<\/span><\/p><figure id=\"attachment_44005\" aria-describedby=\"caption-attachment-44005\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-44005 size-full\" src=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"2039\" srcset=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-scaled.jpg 2560w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-300x239.jpg 300w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-1024x816.jpg 1024w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-768x612.jpg 768w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-1536x1224.jpg 1536w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-2048x1632.jpg 2048w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-370x295.jpg 370w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-818x652.jpg 818w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-406x323.jpg 406w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-600x478.jpg 600w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-500x398.jpg 500w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-400x319.jpg 400w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Moullet-10_2025-1-32x25.jpg 32w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-44005\" class=\"wp-caption-text\">Barish Moullet (Young Stars ZH)<\/figcaption><\/figure><p style=\"text-align: justify;\">Apr\u00e8s sa d\u00e9faite lors du premier match ce week-end, Rapperswil-Jona corrige le bilan et remporte des points importants dans la lutte pour les places en play-off gr\u00e2ce \u00e0 sa victoire contre Rio-Star Muttenz (6:4) et son match nul contre Neuhausen (5:5). Le match de samedi est marqu\u00e9 par des d\u00e9roulements passionnants : sur dix matchs, six vont en prolongation et cinq fois, l&rsquo;\u00e9quipe locale de Rapperswil-Jona s&rsquo;impose de justesse contre Muttenz. Martin Guman (A20) fait notamment preuve de nerfs d&rsquo;acier et s&rsquo;impose trois fois au cinqui\u00e8me set, dont deux fois en prolongation. Le h\u00e9ros de ce marathon de quatre heures est toutefois Denis Bernhard (A19), qui bat Numa Ulrich (A19) 15:13 au cinqui\u00e8me set lors du dixi\u00e8me match de la journ\u00e9e, assurant ainsi \u00e0 son \u00e9quipe une victoire serr\u00e9e 6:4, m\u00eame si l&rsquo;adversaire remporte trois sets de plus au total. Lors du match nul contre une \u00e9quipe de Neuhausen tr\u00e8s forte le lendemain, la double victoire de Bernhard et Gon\u00e7alo Gomes (A20) est particuli\u00e8rement importante pour le score global. Guman remporte \u00e0 nouveau deux victoires en simple.<\/p><figure id=\"attachment_43992\" aria-describedby=\"caption-attachment-43992\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-43992 size-full\" src=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-scaled.jpg 2560w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-300x225.jpg 300w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-1024x768.jpg 1024w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-768x576.jpg 768w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-1536x1152.jpg 1536w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-2048x1536.jpg 2048w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-370x278.jpg 370w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-818x614.jpg 818w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-406x305.jpg 406w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-600x450.jpg 600w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-500x375.jpg 500w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-400x300.jpg 400w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2022\/11\/Bernhard-10_2025-2-32x24.jpg 32w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-43992\" class=\"wp-caption-text\">Denis Bernhard (Rapperswil-Jona)<\/figcaption><\/figure><p style=\"text-align: justify;\">Neuhausen occupe quant \u00e0 lui la 6e place : samedi, tout ne se passe pas comme pr\u00e9vu et les joueurs de Neuhausen s&rsquo;inclinent 6:1 face aux Young Stars ZH, la nouvelle recrue Lukas Bosbach (A20) remportant le point d&rsquo;honneur. Dimanche, le meilleur buteur de la saison derni\u00e8re, Zeimys Kestutis (A20), a pu reprendre du service et a assur\u00e9 le match nul 5:5 \u00e0 son \u00e9quipe gr\u00e2ce \u00e0 un bilan individuel impeccable contre Rapperswil-Jona, permettant ainsi \u00e0 Neuhausen de remporter son premier point. Pekka Pelz (A20), qui \u00e9tait rest\u00e9 discret la veille, a contribu\u00e9 aux autres points en battant Gomes et Bernhard.<\/p><p style=\"text-align: justify;\"><span lang=\"DE\">Rio-Star Muttenz reste dernier sans aucun point : en Suisse orientale, les joueurs de Muttenz s&rsquo;inclinent de justesse 4:6 \u00e0 Rapperswil-Jona et 2:6 chez les Young Stars. Le double C\u00e9dric Tschanz (A20)\/Pedro Osiro (A20) est la seule lueur d&rsquo;espoir dans ces deux matchs, prouvant son harmonie et remportant les deux rencontres.<\/span><\/p><figure id=\"attachment_44007\" aria-describedby=\"caption-attachment-44007\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-44007 size-full\" src=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1708\" srcset=\"https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-scaled.jpg 2560w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-300x200.jpg 300w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-1024x683.jpg 1024w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-768x512.jpg 768w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-391x260.jpg 391w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-1536x1025.jpg 1536w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-2048x1366.jpg 2048w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-370x247.jpg 370w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-818x546.jpg 818w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-406x271.jpg 406w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-600x400.jpg 600w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-500x334.jpg 500w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-400x267.jpg 400w, https:\/\/www.swisstabletennis.ch\/wp-content\/uploads\/2025\/10\/Neuhausen-Doppel-10_2025-1-32x21.jpg 32w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-44007\" class=\"wp-caption-text\">Zeimys Kestutis und Pekka Pelz (Neuhausen)<\/figcaption><\/figure>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-276417d e-flex e-con-boxed e-con e-parent\" data-id=\"276417d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83ea67e e-con-full e-flex e-con e-child\" data-id=\"83ea67e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e73623a sc_fly_static elementor-widget elementor-widget-html\" data-id=\"e73623a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><b>STTL Men Ranking:<\/b><\/p>\n\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/tt-mobile-widgets@1.5.1\/tt-mobile.min.js\" type=\"text\/javascript\"><\/script>\n\n<table class=\"mytable\"><\/table>\n<script>TTmobile.table(\"groupPage?championship=STT+25%2F26&group=216984\", document.querySelector(\".mytable\"), { logoSize: \"0\"});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73e55d4 e-con-full e-flex e-con e-child\" data-id=\"73e55d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea18ba3 sc_fly_static elementor-widget elementor-widget-html\" data-id=\"ea18ba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><b>STTL Women Ranking:<\/b><\/p>\n<script src=\"https:\/\/cdn.jsdelivr.net\/npm\/tt-mobile-widgets@1.5.1\/tt-mobile.min.js\" type=\"text\/javascript\"><\/script>\n\n<table class=\"mytable1\"><\/table>\n<script>TTmobile.table(\"groupPage?championship=STT+25%2F26&group=216985\", document.querySelector(\".mytable1\"), { logoSize: \"0\"});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Les 25 et 26 octobre ont eu lieu les 3e et 4e tours de la Swiss Table Tennis League Men&hellip;<\/p>\n","protected":false},"author":14,"featured_media":37911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[471],"tags":[],"class_list":["post-44019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sttl-swiss-table-tennis-league"],"_links":{"self":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts\/44019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/comments?post=44019"}],"version-history":[{"count":12,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts\/44019\/revisions"}],"predecessor-version":[{"id":44046,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/posts\/44019\/revisions\/44046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/media\/37911"}],"wp:attachment":[{"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/media?parent=44019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/categories?post=44019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swisstabletennis.ch\/fr\/wp-json\/wp\/v2\/tags?post=44019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}